{"id":738,"date":"2019-06-12T12:46:47","date_gmt":"2019-06-12T12:46:47","guid":{"rendered":"http:\/\/traksler.co\/?page_id=738"},"modified":"2019-06-24T12:34:53","modified_gmt":"2019-06-24T12:34:53","slug":"duboki-tanjir","status":"publish","type":"page","link":"https:\/\/traksler.co\/en\/duboki-tanjir\/","title":{"rendered":"deep plates"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"738\" class=\"elementor elementor-738\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6244ec5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6244ec5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fde7f3e\" data-id=\"fde7f3e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3287935 elementor-widget elementor-widget-spacer\" data-id=\"3287935\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31a0dff elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"31a0dff\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">deep plates<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-986e833 elementor-widget elementor-widget-spacer\" data-id=\"986e833\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0637d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"f0637d9\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3dd88cd\" data-id=\"3dd88cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ec51b8 elementor-widget elementor-widget-image-gallery\" data-id=\"0ec51b8\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-738 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0ec51b8\" data-elementor-lightbox-title=\"tanjir-tresnja\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODQ3LCJ1cmwiOiJodHRwczpcL1wvdHJha3NsZXIuY29cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMTlcLzA2XC90YW5qaXItdHJlc25qYS5qcGciLCJzbGlkZXNob3ciOiIwZWM1MWI4In0%3D\" href='https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"1980\" height=\"1315\" src=\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja.jpg 1980w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja-300x199.jpg 300w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja-768x510.jpg 768w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja-1024x680.jpg 1024w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja-600x398.jpg 600w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0ec51b8\" data-elementor-lightbox-title=\"tresnja-tanjir-3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODQ4LCJ1cmwiOiJodHRwczpcL1wvdHJha3NsZXIuY29cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMTlcLzA2XC90cmVzbmphLXRhbmppci0zLmpwZyIsInNsaWRlc2hvdyI6IjBlYzUxYjgifQ%3D%3D\" href='https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-3.jpg'><img decoding=\"async\" width=\"1980\" height=\"1315\" src=\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-3.jpg 1980w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-3-300x199.jpg 300w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-3-768x510.jpg 768w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-3-1024x680.jpg 1024w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-3-600x398.jpg 600w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0ec51b8\" data-elementor-lightbox-title=\"posuda-orah\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODQ5LCJ1cmwiOiJodHRwczpcL1wvdHJha3NsZXIuY29cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMTlcLzA2XC9wb3N1ZGEtb3JhaC0xLmpwZyIsInNsaWRlc2hvdyI6IjBlYzUxYjgifQ%3D%3D\" href='https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/posuda-orah-1.jpg'><img decoding=\"async\" width=\"1980\" height=\"1315\" src=\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/posuda-orah-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/posuda-orah-1.jpg 1980w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/posuda-orah-1-300x199.jpg 300w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/posuda-orah-1-768x510.jpg 768w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/posuda-orah-1-1024x680.jpg 1024w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/posuda-orah-1-600x398.jpg 600w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0ec51b8\" data-elementor-lightbox-title=\"tanjir-tresnja-1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODI2LCJ1cmwiOiJodHRwczpcL1wvdHJha3NsZXIuY29cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMTlcLzA2XC90YW5qaXItdHJlc25qYS0xLmpwZyIsInNsaWRlc2hvdyI6IjBlYzUxYjgifQ%3D%3D\" href='https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"1315\" src=\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja-1.jpg 1980w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja-1-300x199.jpg 300w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja-1-768x510.jpg 768w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja-1-1024x680.jpg 1024w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja-1-600x398.jpg 600w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0ec51b8\" data-elementor-lightbox-title=\"tresnja-tanjir-2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODI3LCJ1cmwiOiJodHRwczpcL1wvdHJha3NsZXIuY29cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMTlcLzA2XC90cmVzbmphLXRhbmppci0yLmpwZyIsInNsaWRlc2hvdyI6IjBlYzUxYjgifQ%3D%3D\" href='https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"1315\" src=\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-2.jpg 1980w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-2-300x199.jpg 300w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-2-768x510.jpg 768w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-2-1024x680.jpg 1024w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-2-600x398.jpg 600w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-59ab00d elementor-hidden-phone\" data-id=\"59ab00d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75de6e4 elementor-widget elementor-widget-image\" data-id=\"75de6e4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-3-1024x680.jpg\" class=\"attachment-large size-large wp-image-848\" alt=\"\" srcset=\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-3-1024x680.jpg 1024w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-3-300x199.jpg 300w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-3-768x510.jpg 768w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-3-600x398.jpg 600w, https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tresnja-tanjir-3.jpg 1980w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24679da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24679da\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7cbac3f\" data-id=\"7cbac3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b0b2c2 elementor-widget elementor-widget-text-editor\" data-id=\"4b0b2c2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>deep plates are made of one piece of wood, most often cherry, alder, oak, walnut, pear. they are protected by natural oil certified for direct contact with food.<\/p><p>dimensions: wooden plates are hand-made. plate width is 18cm + -2mm and height 4.5cm + -2mm.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>duboki tanjir duboki tanjiri se prave iz jednog komada drveta, naj\u010de\u0161\u0107e tre\u0161nje, johe, hrasta, oraha, kru\u0161ke. za\u0161ti\u0107eni su prirodnim uljem sertifikovanim za direktan kontakt sa hranom. dimenzije: drveni tanjiri su ru\u010dne izrade. pre\u010dnik tanjira je 18cm +-2mm a visina 4,5cm +-2mm.<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-738","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>duboki tanjir - traksler<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/traksler.co\/en\/duboki-tanjir\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"duboki tanjir - traksler\" \/>\n<meta property=\"og:description\" content=\"duboki tanjir duboki tanjiri se prave iz jednog komada drveta, naj\u010de\u0161\u0107e tre\u0161nje, johe, hrasta, oraha, kru\u0161ke. za\u0161ti\u0107eni su prirodnim uljem sertifikovanim za direktan kontakt sa hranom. dimenzije: drveni tanjiri su ru\u010dne izrade. pre\u010dnik tanjira je 18cm +-2mm a visina 4,5cm +-2mm.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/traksler.co\/en\/duboki-tanjir\/\" \/>\n<meta property=\"og:site_name\" content=\"traksler\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trakslershapeswood\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-24T12:34:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/traksler.co\/duboki-tanjir\/\",\"url\":\"https:\/\/traksler.co\/duboki-tanjir\/\",\"name\":\"duboki tanjir - traksler\",\"isPartOf\":{\"@id\":\"https:\/\/traksler.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/traksler.co\/duboki-tanjir\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/traksler.co\/duboki-tanjir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja.jpg\",\"datePublished\":\"2019-06-12T12:46:47+00:00\",\"dateModified\":\"2019-06-24T12:34:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/traksler.co\/duboki-tanjir\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/traksler.co\/duboki-tanjir\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/traksler.co\/duboki-tanjir\/#primaryimage\",\"url\":\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja.jpg\",\"contentUrl\":\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/traksler.co\/duboki-tanjir\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/traksler.co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"duboki tanjir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/traksler.co\/#website\",\"url\":\"https:\/\/traksler.co\/\",\"name\":\"traksler\",\"description\":\"wood products\",\"publisher\":{\"@id\":\"https:\/\/traksler.co\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/traksler.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/traksler.co\/#organization\",\"name\":\"traksler\",\"url\":\"https:\/\/traksler.co\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/traksler.co\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/01\/vertikalni.jpg\",\"contentUrl\":\"https:\/\/traksler.co\/wp-content\/uploads\/2019\/01\/vertikalni.jpg\",\"width\":2158,\"height\":2494,\"caption\":\"traksler\"},\"image\":{\"@id\":\"https:\/\/traksler.co\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/trakslershapeswood\/\",\"https:\/\/www.instagram.com\/traksler_shapeswood\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"duboki tanjir - traksler","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/traksler.co\/en\/duboki-tanjir\/","og_locale":"en_US","og_type":"article","og_title":"duboki tanjir - traksler","og_description":"duboki tanjir duboki tanjiri se prave iz jednog komada drveta, naj\u010de\u0161\u0107e tre\u0161nje, johe, hrasta, oraha, kru\u0161ke. za\u0161ti\u0107eni su prirodnim uljem sertifikovanim za direktan kontakt sa hranom. dimenzije: drveni tanjiri su ru\u010dne izrade. pre\u010dnik tanjira je 18cm +-2mm a visina 4,5cm +-2mm.","og_url":"https:\/\/traksler.co\/en\/duboki-tanjir\/","og_site_name":"traksler","article_publisher":"https:\/\/www.facebook.com\/trakslershapeswood\/","article_modified_time":"2019-06-24T12:34:53+00:00","og_image":[{"url":"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/traksler.co\/duboki-tanjir\/","url":"https:\/\/traksler.co\/duboki-tanjir\/","name":"duboki tanjir - traksler","isPartOf":{"@id":"https:\/\/traksler.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/traksler.co\/duboki-tanjir\/#primaryimage"},"image":{"@id":"https:\/\/traksler.co\/duboki-tanjir\/#primaryimage"},"thumbnailUrl":"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja.jpg","datePublished":"2019-06-12T12:46:47+00:00","dateModified":"2019-06-24T12:34:53+00:00","breadcrumb":{"@id":"https:\/\/traksler.co\/duboki-tanjir\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/traksler.co\/duboki-tanjir\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/traksler.co\/duboki-tanjir\/#primaryimage","url":"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja.jpg","contentUrl":"https:\/\/traksler.co\/wp-content\/uploads\/2019\/06\/tanjir-tresnja.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/traksler.co\/duboki-tanjir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/traksler.co\/"},{"@type":"ListItem","position":2,"name":"duboki tanjir"}]},{"@type":"WebSite","@id":"https:\/\/traksler.co\/#website","url":"https:\/\/traksler.co\/","name":"traksler","description":"wood products","publisher":{"@id":"https:\/\/traksler.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/traksler.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/traksler.co\/#organization","name":"traksler","url":"https:\/\/traksler.co\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/traksler.co\/#\/schema\/logo\/image\/","url":"https:\/\/traksler.co\/wp-content\/uploads\/2019\/01\/vertikalni.jpg","contentUrl":"https:\/\/traksler.co\/wp-content\/uploads\/2019\/01\/vertikalni.jpg","width":2158,"height":2494,"caption":"traksler"},"image":{"@id":"https:\/\/traksler.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trakslershapeswood\/","https:\/\/www.instagram.com\/traksler_shapeswood\/"]}]}},"_links":{"self":[{"href":"https:\/\/traksler.co\/en\/wp-json\/wp\/v2\/pages\/738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/traksler.co\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/traksler.co\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/traksler.co\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/traksler.co\/en\/wp-json\/wp\/v2\/comments?post=738"}],"version-history":[{"count":6,"href":"https:\/\/traksler.co\/en\/wp-json\/wp\/v2\/pages\/738\/revisions"}],"predecessor-version":[{"id":1033,"href":"https:\/\/traksler.co\/en\/wp-json\/wp\/v2\/pages\/738\/revisions\/1033"}],"wp:attachment":[{"href":"https:\/\/traksler.co\/en\/wp-json\/wp\/v2\/media?parent=738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}